{"id":1412,"date":"2025-03-14T18:35:23","date_gmt":"2025-03-14T09:35:23","guid":{"rendered":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/"},"modified":"2026-04-08T15:25:48","modified_gmt":"2026-04-08T06:25:48","slug":"equipment-k-41","status":"publish","type":"equipment","link":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/","title":{"rendered":"\u30ea\u30a2\u30eb\u30bf\u30a4\u30e0\uff30\uff23\uff32\u30b7\u30b9\u30c6\u30e0"},"featured_media":1313,"parent":0,"template":"","equipment_category":[291],"equipment_purpose":[286],"equipment_location":[285],"class_list":["post-1412","equipment","type-equipment","status-publish","has-post-thumbnail","hentry","equipment_category-gse","equipment_purpose-analysis","equipment_location-katsurayui"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u30ea\u30a2\u30eb\u30bf\u30a4\u30e0\uff30\uff23\uff32\u30b7\u30b9\u30c6\u30e0 | \u4eac\u90fd\u5927\u5b66 \u5b87\u6cbb\u5730\u533a\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8<\/title>\n<meta name=\"description\" content=\"\u5b87\u6cbb\u5730\u533a\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8\u62e0\u70b9\u306f\u3001\u4eac\u90fd\u30fb\u5b87\u6cbb\u30ad\u30e3\u30f3\u30d1\u30b9\u306e\u5171\u7528\u6a5f\u6a5f\u60c5\u5831\u306e\u30cf\u30d6\u3068\u3057\u3066\u7814\u7a76\u8005\u3092\u30b5\u30dd\u30fc\u30c8\u3057\u307e\u3059\u3002\u3053\u306e\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8\u3067\u306f\u3001\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8\u62e0\u70b9\u306b\u767b\u9332\u3055\u308c\u3066\u3044\u308b\u5171\u7528\u6a5f\u6a5f\u3001\u8a2d\u7f6e\u5834\u6240\u3001\u5229\u7528\u624b\u9806\u304c\u691c\u7d22\u3067\u304d\u307e\u3059\u3002\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u30ea\u30a2\u30eb\u30bf\u30a4\u30e0\uff30\uff23\uff32\u30b7\u30b9\u30c6\u30e0 | \u4eac\u90fd\u5927\u5b66 \u5b87\u6cbb\u5730\u533a\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/\" \/>\n<meta property=\"og:site_name\" content=\"\u4eac\u90fd\u5927\u5b66 \u5b87\u6cbb\u5730\u533a\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T06:25:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/wp-content\/uploads\/2025\/03\/k-41-115004-A-004.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/\",\"url\":\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/\",\"name\":\"\u30ea\u30a2\u30eb\u30bf\u30a4\u30e0\uff30\uff23\uff32\u30b7\u30b9\u30c6\u30e0 | \u4eac\u90fd\u5927\u5b66 \u5b87\u6cbb\u5730\u533a\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8\",\"isPartOf\":{\"@id\":\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/#website\"},\"datePublished\":\"2025-03-14T09:35:23+00:00\",\"dateModified\":\"2026-04-08T06:25:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u6a5f\u5668\u8a73\u7d30\",\"item\":\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u30ea\u30a2\u30eb\u30bf\u30a4\u30e0\uff30\uff23\uff32\u30b7\u30b9\u30c6\u30e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/#website\",\"url\":\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/\",\"name\":\"\u4eac\u90fd\u5927\u5b66 \u5b87\u6cbb\u5730\u533a\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ja\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u30ea\u30a2\u30eb\u30bf\u30a4\u30e0\uff30\uff23\uff32\u30b7\u30b9\u30c6\u30e0 | \u4eac\u90fd\u5927\u5b66 \u5b87\u6cbb\u5730\u533a\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8","description":"\u5b87\u6cbb\u5730\u533a\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8\u62e0\u70b9\u306f\u3001\u4eac\u90fd\u30fb\u5b87\u6cbb\u30ad\u30e3\u30f3\u30d1\u30b9\u306e\u5171\u7528\u6a5f\u6a5f\u60c5\u5831\u306e\u30cf\u30d6\u3068\u3057\u3066\u7814\u7a76\u8005\u3092\u30b5\u30dd\u30fc\u30c8\u3057\u307e\u3059\u3002\u3053\u306e\u30a6\u30a7\u30d6\u30b5\u30a4\u30c8\u3067\u306f\u3001\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8\u62e0\u70b9\u306b\u767b\u9332\u3055\u308c\u3066\u3044\u308b\u5171\u7528\u6a5f\u6a5f\u3001\u8a2d\u7f6e\u5834\u6240\u3001\u5229\u7528\u624b\u9806\u304c\u691c\u7d22\u3067\u304d\u307e\u3059\u3002","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/","og_locale":"ja_JP","og_type":"article","og_title":"\u30ea\u30a2\u30eb\u30bf\u30a4\u30e0\uff30\uff23\uff32\u30b7\u30b9\u30c6\u30e0 | \u4eac\u90fd\u5927\u5b66 \u5b87\u6cbb\u5730\u533a\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8","og_url":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/","og_site_name":"\u4eac\u90fd\u5927\u5b66 \u5b87\u6cbb\u5730\u533a\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8","article_modified_time":"2026-04-08T06:25:48+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/wp-content\/uploads\/2025\/03\/k-41-115004-A-004.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/","url":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/","name":"\u30ea\u30a2\u30eb\u30bf\u30a4\u30e0\uff30\uff23\uff32\u30b7\u30b9\u30c6\u30e0 | \u4eac\u90fd\u5927\u5b66 \u5b87\u6cbb\u5730\u533a\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8","isPartOf":{"@id":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/#website"},"datePublished":"2025-03-14T09:35:23+00:00","dateModified":"2026-04-08T06:25:48+00:00","breadcrumb":{"@id":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/equipment-k-41\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/"},{"@type":"ListItem","position":2,"name":"\u6a5f\u5668\u8a73\u7d30","item":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/equipment\/"},{"@type":"ListItem","position":3,"name":"\u30ea\u30a2\u30eb\u30bf\u30a4\u30e0\uff30\uff23\uff32\u30b7\u30b9\u30c6\u30e0"}]},{"@type":"WebSite","@id":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/#website","url":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/","name":"\u4eac\u90fd\u5927\u5b66 \u5b87\u6cbb\u5730\u533a\u8a2d\u5099\u30b5\u30dd\u30fc\u30c8","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ja"}]}},"_links":{"self":[{"href":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/wp-json\/wp\/v2\/equipment\/1412"}],"collection":[{"href":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/wp-json\/wp\/v2\/equipment"}],"about":[{"href":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/wp-json\/wp\/v2\/types\/equipment"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/wp-json\/wp\/v2\/media\/1313"}],"wp:attachment":[{"href":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/wp-json\/wp\/v2\/media?parent=1412"}],"wp:term":[{"taxonomy":"equipment_category","embeddable":true,"href":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/wp-json\/wp\/v2\/equipment_category?post=1412"},{"taxonomy":"equipment_purpose","embeddable":true,"href":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/wp-json\/wp\/v2\/equipment_purpose?post=1412"},{"taxonomy":"equipment_location","embeddable":true,"href":"https:\/\/www.jimu.uji.kyoto-u.ac.jp\/uji-sces\/wp-json\/wp\/v2\/equipment_location?post=1412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}